{"id":43331,"date":"2020-12-23T12:09:48","date_gmt":"2020-12-23T17:09:48","guid":{"rendered":"http:\/\/portal.compraspublicas.gob.ec\/sercop\/?page_id=43331"},"modified":"2024-11-28T12:04:18","modified_gmt":"2024-11-28T17:04:18","slug":"cifras-de-la-contratacion-publica-noviembre","status":"publish","type":"page","link":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/cifras-de-la-contratacion-publica-noviembre\/","title":{"rendered":"Cifras de la Contrataci\u00f3n P\u00fablica-Noviembre"},"content":{"rendered":"<p style=\"display:flex\">\n<img loading=\"lazy\" class=\"alignnone size-full wp-image-42169\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/cabecera_principal-1.jpg\" alt=\"\" width=\"900\" height=\"192\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/cabecera_principal-1.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/cabecera_principal-1-300x64.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/cabecera_principal-1-768x164.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-19-at-11.57.37-AM.jpeg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42702\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-19-at-11.57.37-AM.jpeg\" alt=\"\" width=\"1132\" height=\"132\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-19-at-11.57.37-AM.jpeg 1132w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-19-at-11.57.37-AM-300x35.jpeg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-19-at-11.57.37-AM-768x90.jpeg 768w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-19-at-11.57.37-AM-1024x119.jpeg 1024w\" sizes=\"(max-width: 1132px) 100vw, 1132px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/10\/WhatsApp-Image-2020-10-19-at-11.29.43-AM.jpeg\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42700\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/12\/NOVIEMBRE.png\" alt=\"\" width=\"1132\" height=\"66\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/cp_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42203\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/compras_publicas.jpg\" alt=\"\" width=\"900\" height=\"52\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/compras_publicas.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/compras_publicas-300x17.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/compras_publicas-768x44.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-42200\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/regimen_comun_1.jpg\" alt=\"\" width=\"900\" height=\"54\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/regimen_comun_1.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/regimen_comun_1-300x18.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/regimen_comun_1-768x46.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/sie_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42205\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/subasta_inversa_1-1.jpg\" alt=\"\" width=\"900\" height=\"54\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/subasta_inversa_1-1.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/subasta_inversa_1-1-300x18.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/subasta_inversa_1-1-768x46.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/ce_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42206\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/catalogo_1-1.jpg\" alt=\"\" width=\"900\" height=\"54\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/catalogo_1-1.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/catalogo_1-1-300x18.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/catalogo_1-1-768x46.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/resto_rc_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42197\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/licitacion_1.jpg\" alt=\"\" width=\"900\" height=\"53\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/licitacion_1.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/licitacion_1-300x18.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/licitacion_1-768x45.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/consul_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42204\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/consultoria.jpg\" alt=\"\" width=\"900\" height=\"56\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/consultoria.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/consultoria-300x19.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/consultoria-768x48.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/fi_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42224\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_fi.jpg\" alt=\"\" width=\"900\" height=\"53\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_fi.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_fi-300x18.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_fi-768x45.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/re_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42227\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_re_1.jpg\" alt=\"\" width=\"900\" height=\"54\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_re_1.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_re_1-300x18.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_re_1-768x46.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><img loading=\"lazy\" class=\"alignnone size-full wp-image-42232\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM1.jpeg\" alt=\"\" width=\"900\" height=\"55\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM1.jpeg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM1-300x18.jpeg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM1-768x47.jpeg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/emer_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42233\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM.jpeg\" alt=\"\" width=\"900\" height=\"54\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM.jpeg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM-300x18.jpeg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/WhatsApp-Image-2020-08-18-at-12.41.25-PM-768x46.jpeg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/infi_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42226\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_ic_1-1.png\" alt=\"\" width=\"900\" height=\"52\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_ic_1-1.png 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_ic_1-1-300x17.png 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_ic_1-1-768x44.png 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/aabi_nov2020.xlsm\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42221\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_aabi.jpg\" alt=\"\" width=\"900\" height=\"53\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_aabi.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_aabi-300x18.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_aabi-768x45.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n<p><a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/manual_de_usuario.docx\"><img loading=\"lazy\" class=\"alignnone size-full wp-image-42222\" src=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_manual.jpg\" alt=\"\" width=\"900\" height=\"52\" srcset=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_manual.jpg 900w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_manual-300x17.jpg 300w, https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-content\/uploads\/2020\/08\/boton_manual-768x44.jpg 768w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p class=\"excerpt\"> <a href=\"https:\/\/portal.compraspublicas.gob.ec\/sercop\/cifras-de-la-contratacion-publica-noviembre\/\">Read more &rarr;<\/a><\/p>\n","protected":false},"author":75,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"menugenerico.php","meta":[],"_links":{"self":[{"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/pages\/43331"}],"collection":[{"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/users\/75"}],"replies":[{"embeddable":true,"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/comments?post=43331"}],"version-history":[{"count":4,"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/pages\/43331\/revisions"}],"predecessor-version":[{"id":60326,"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/pages\/43331\/revisions\/60326"}],"wp:attachment":[{"href":"https:\/\/portal.compraspublicas.gob.ec\/sercop\/wp-json\/wp\/v2\/media?parent=43331"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}